{"id":25293,"date":"2026-06-02T07:58:05","date_gmt":"2026-06-01T21:58:05","guid":{"rendered":"http:\/\/homeshows.com.au\/sydney\/exhibitor\/sydney-professional-kitchens\/"},"modified":"2026-09-02T21:00:58","modified_gmt":"2026-09-02T11:00:58","slug":"sydney-professional-kitchens","status":"publish","type":"exhibitor","link":"https:\/\/homeshows.com.au\/sydney\/exhibitor\/sydney-professional-kitchens\/","title":{"rendered":"Sydney Professional Kitchens"},"content":{"rendered":"","protected":false},"featured_media":0,"parent":0,"template":"","exhibitor-category":[334,355],"month":[],"class_list":["post-25293","exhibitor","type-exhibitor","status-publish","hentry","exhibitor-category-kitchens-kitchen-products","exhibitor-category-wardrobes-storage-solutions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sydney Professional Kitchens - Sydney Home Show<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/homeshows.com.au\/sydney\/exhibitor\/sydney-professional-kitchens\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sydney Professional Kitchens - Sydney Home Show\" \/>\n<meta property=\"og:url\" content=\"https:\/\/homeshows.com.au\/sydney\/exhibitor\/sydney-professional-kitchens\/\" \/>\n<meta property=\"og:site_name\" content=\"Sydney Home Show\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/homeshowaustralia\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-02T11:00:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/homeshows.com.au\/sydney\/wp-content\/uploads\/sites\/6\/2024\/02\/Imperial-no-state.png\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"325\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/homeshows.com.au\\\/sydney\\\/exhibitor\\\/sydney-professional-kitchens\\\/\",\"url\":\"https:\\\/\\\/homeshows.com.au\\\/sydney\\\/exhibitor\\\/sydney-professional-kitchens\\\/\",\"name\":\"Sydney Professional Kitchens - Sydney Home Show\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/homeshows.com.au\\\/sydney\\\/#website\"},\"datePublished\":\"2026-06-01T21:58:05+00:00\",\"dateModified\":\"2026-09-02T11:00:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/homeshows.com.au\\\/sydney\\\/exhibitor\\\/sydney-professional-kitchens\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/homeshows.com.au\\\/sydney\\\/exhibitor\\\/sydney-professional-kitchens\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/homeshows.com.au\\\/sydney\\\/exhibitor\\\/sydney-professional-kitchens\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/homeshows.com.au\\\/sydney\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sydney Professional Kitchens\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/homeshows.com.au\\\/sydney\\\/#website\",\"url\":\"https:\\\/\\\/homeshows.com.au\\\/sydney\\\/\",\"name\":\"Sydney Home Show\",\"description\":\"Australia&#039;s premium home improvement exhibition\u200b\",\"publisher\":{\"@id\":\"https:\\\/\\\/homeshows.com.au\\\/sydney\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/homeshows.com.au\\\/sydney\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/homeshows.com.au\\\/sydney\\\/#organization\",\"name\":\"Sydney Home Show\",\"url\":\"https:\\\/\\\/homeshows.com.au\\\/sydney\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/homeshows.com.au\\\/sydney\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/homeshows.com.au\\\/sydney\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/02\\\/Imperial-no-state.png\",\"contentUrl\":\"https:\\\/\\\/homeshows.com.au\\\/sydney\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/02\\\/Imperial-no-state.png\",\"width\":500,\"height\":325,\"caption\":\"Sydney Home Show\"},\"image\":{\"@id\":\"https:\\\/\\\/homeshows.com.au\\\/sydney\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/homeshowaustralia\\\/\",\"https:\\\/\\\/www.instagram.com\\\/homeshowaustralia\",\"https:\\\/\\\/www.tiktok.com\\\/@homeshowaustralia\",\"https:\\\/\\\/www.youtube.com\\\/@homeshowaustralia\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sydney Professional Kitchens - Sydney Home Show","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/homeshows.com.au\/sydney\/exhibitor\/sydney-professional-kitchens\/","og_locale":"en_US","og_type":"article","og_title":"Sydney Professional Kitchens - Sydney Home Show","og_url":"https:\/\/homeshows.com.au\/sydney\/exhibitor\/sydney-professional-kitchens\/","og_site_name":"Sydney Home Show","article_publisher":"https:\/\/www.facebook.com\/homeshowaustralia\/","article_modified_time":"2026-09-02T11:00:58+00:00","og_image":[{"width":500,"height":325,"url":"https:\/\/homeshows.com.au\/sydney\/wp-content\/uploads\/sites\/6\/2024\/02\/Imperial-no-state.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/homeshows.com.au\/sydney\/exhibitor\/sydney-professional-kitchens\/","url":"https:\/\/homeshows.com.au\/sydney\/exhibitor\/sydney-professional-kitchens\/","name":"Sydney Professional Kitchens - Sydney Home Show","isPartOf":{"@id":"https:\/\/homeshows.com.au\/sydney\/#website"},"datePublished":"2026-06-01T21:58:05+00:00","dateModified":"2026-09-02T11:00:58+00:00","breadcrumb":{"@id":"https:\/\/homeshows.com.au\/sydney\/exhibitor\/sydney-professional-kitchens\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/homeshows.com.au\/sydney\/exhibitor\/sydney-professional-kitchens\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/homeshows.com.au\/sydney\/exhibitor\/sydney-professional-kitchens\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/homeshows.com.au\/sydney\/"},{"@type":"ListItem","position":2,"name":"Sydney Professional Kitchens"}]},{"@type":"WebSite","@id":"https:\/\/homeshows.com.au\/sydney\/#website","url":"https:\/\/homeshows.com.au\/sydney\/","name":"Sydney Home Show","description":"Australia&#039;s premium home improvement exhibition\u200b","publisher":{"@id":"https:\/\/homeshows.com.au\/sydney\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/homeshows.com.au\/sydney\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/homeshows.com.au\/sydney\/#organization","name":"Sydney Home Show","url":"https:\/\/homeshows.com.au\/sydney\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/homeshows.com.au\/sydney\/#\/schema\/logo\/image\/","url":"https:\/\/homeshows.com.au\/sydney\/wp-content\/uploads\/sites\/6\/2024\/02\/Imperial-no-state.png","contentUrl":"https:\/\/homeshows.com.au\/sydney\/wp-content\/uploads\/sites\/6\/2024\/02\/Imperial-no-state.png","width":500,"height":325,"caption":"Sydney Home Show"},"image":{"@id":"https:\/\/homeshows.com.au\/sydney\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/homeshowaustralia\/","https:\/\/www.instagram.com\/homeshowaustralia","https:\/\/www.tiktok.com\/@homeshowaustralia","https:\/\/www.youtube.com\/@homeshowaustralia"]}]}},"_links":{"self":[{"href":"https:\/\/homeshows.com.au\/sydney\/wp-json\/wp\/v2\/exhibitor\/25293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/homeshows.com.au\/sydney\/wp-json\/wp\/v2\/exhibitor"}],"about":[{"href":"https:\/\/homeshows.com.au\/sydney\/wp-json\/wp\/v2\/types\/exhibitor"}],"wp:attachment":[{"href":"https:\/\/homeshows.com.au\/sydney\/wp-json\/wp\/v2\/media?parent=25293"}],"wp:term":[{"taxonomy":"exhibitor-category","embeddable":true,"href":"https:\/\/homeshows.com.au\/sydney\/wp-json\/wp\/v2\/exhibitor-category?post=25293"},{"taxonomy":"month","embeddable":true,"href":"https:\/\/homeshows.com.au\/sydney\/wp-json\/wp\/v2\/month?post=25293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}